{"id":24207,"date":"2020-08-05T12:54:27","date_gmt":"2020-08-05T16:54:27","guid":{"rendered":"https:\/\/voxy.com\/?p=24207"},"modified":"2020-11-20T13:08:03","modified_gmt":"2020-11-20T18:08:03","slug":"a-transformacao-digital-no-ensino-de-idiomas","status":"publish","type":"post","link":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/","title":{"rendered":"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O termo &#8220;transforma\u00e7\u00e3o digital&#8221; n\u00e3o \u00e9 nada novo e vem sendo usado em diversos contextos h\u00e1 algum tempo, mas os acontecimentos recentes que levaram cidades e pa\u00edses inteiros a adotarem pol\u00edticas de isolamento social fez com que o processo da transforma\u00e7\u00e3o digital fosse acelerado em organiza\u00e7\u00f5es que precisaram se <\/span><b>adaptar \u00e0s mudan\u00e7as<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A transforma\u00e7\u00e3o digital nada mais \u00e9 que o processo no qual uma organiza\u00e7\u00e3o adota uma <\/span><b>abordagem digital <\/b><span style=\"font-weight: 400;\">em suas atividades, utilizando ferramentas e t\u00e9cnicas que permitam maior agilidade, flexibilidade, controle e otimiza\u00e7\u00e3o no uso dos recursos envolvidos, resultando em <\/span><a href=\"https:\/\/mobiliza.com.br\/pra-que-serve-treinamento-e-desenvolvimento-nas-empresas\/\" target=\"_blank\" rel=\"noopener noreferrer\"><b>melhores resultados de neg\u00f3cio<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Obviamente que as medidas de distanciamento social e quarentena adotadas ao redor do mundo impactaram, se n\u00e3o todos, a grande maioria dos setores econ\u00f4micos, mas especialmente no<\/span><b> setor educacional <\/b><span style=\"font-weight: 400;\">foi poss\u00edvel observar um grande movimento no sentido de adequar toda a estrutura das institui\u00e7\u00f5es de ensino para manter os neg\u00f3cios funcionando e a continuidade do aprendizado de seus alunos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Conforme a quarentena era instaurada pelo pa\u00eds, muitas pessoas pensaram em aproveitar o tempo extra em suas rotinas para se dedicarem ao <\/span><b>aprendizado de um novo idioma<\/b><span style=\"font-weight: 400;\">. Claramente isso gera uma grande oportunidade para escolas de idiomas &#8211; principalmente para o ingl\u00eas, que \u00e9 uma das l\u00ednguas mais faladas no mundo e uma das mais requisitadas no mercado de trabalho &#8211; mas tamb\u00e9m gera a necessidade dessas escolas correrem atr\u00e1s da transforma\u00e7\u00e3o digital para poderem de fato<\/span><b> atender a essa nova demanda<\/b><span style=\"font-weight: 400;\"> por seus servi\u00e7os.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Acompanhando essa movimenta\u00e7\u00e3o de perto, n\u00f3s aqui na Voxy separamos alguns <\/span><b>pontos importantes <\/b><span style=\"font-weight: 400;\">para voc\u00ea levar em considera\u00e7\u00e3o ao iniciar a transforma\u00e7\u00e3o digital da sua escola de ingl\u00eas para atingir os melhores resultados poss\u00edveis neste cen\u00e1rio.<\/span><\/p>\n<h2><b>Disponibilize conte\u00fado adequado ao ensino digital<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Assim como na educa\u00e7\u00e3o presencial, no ensino online tamb\u00e9m \u00e9 necess\u00e1rio que seu curr\u00edculo e <\/span><b>cat\u00e1logo de conte\u00fado seja de alta qualidade <\/b><span style=\"font-weight: 400;\">para proporcionar um aprendizado efetivo. A diferen\u00e7a \u00e9 que no mundo digital \u00e9 ainda mais importante que voc\u00ea ofere\u00e7a esse material de <a href=\"https:\/\/mobiliza.com.br\/cursos-prontos-ou-cursos-customizados-treinamento-online\/\" target=\"_blank\" rel=\"noopener noreferrer\">forma adaptada e personalizada<\/a>.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Os alunos precisam ter acesso a materiais com os quais eles se identifiquem e sintam-se <\/span><b>engajados<\/b><span style=\"font-weight: 400;\"> para estudar, fazendo com que tenham <\/span><b>maior ader\u00eancia <\/b><span style=\"font-weight: 400;\">aos momentos de aprendizado por conta pr\u00f3pria e aumentando tamb\u00e9m a absor\u00e7\u00e3o do conhecimento transmitido em cada li\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Oferecer uma cole\u00e7\u00e3o <\/span><b>diversa<\/b><span style=\"font-weight: 400;\"> de conte\u00fado educacional, facilmente <\/span><b>acess\u00edvel<\/b><span style=\"font-weight: 400;\">, constantemente <\/span><b>atualizada<\/b><span style=\"font-weight: 400;\"> e com diversos<\/span><b> tipos diferentes<\/b><span style=\"font-weight: 400;\"> de abordagem do ensino \u00e9 essencial para garantir o engajamento dos estudantes.<\/span><\/p>\n<h2><b>Equipe e prepare seus professores<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Ferramentas digitais s\u00e3o imprescind\u00edveis para sua escola realizar uma transforma\u00e7\u00e3o digital completa, mas vale lembrar que elas s\u00e3o <\/span><b>complementares<\/b><span style=\"font-weight: 400;\"> &#8211; e n\u00e3o substitutas &#8211; aos esfor\u00e7os da sua equipe de professores. Aqui na Voxy sempre falamos: usar <\/span><b>software<\/b><span style=\"font-weight: 400;\"> para aproveitar o potencial da <\/span><b>tecnologia<\/b><span style=\"font-weight: 400;\">, permitindo que as <\/span><b>pessoas<\/b><span style=\"font-weight: 400;\"> explorem o potencial dos <\/span><b>humanos<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Seus professores precisam ter em m\u00e3os ferramentas digitais que possibilitem a<\/span><b> maximiza\u00e7\u00e3o de suas potencialidades<\/b><span style=\"font-weight: 400;\">. Isso significa n\u00e3o s\u00f3 uma solu\u00e7\u00e3o de videoconfer\u00eancia entre professor e estudante como tamb\u00e9m uma plataforma para gerenciamento da agenda de aulas ao vivo, pain\u00e9is de monitoramento do desempenho de cada turma ou aluno espec\u00edfico e, claramente, o treinamento adequado de cada uma dessas solu\u00e7\u00f5es.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Assim como voc\u00ea, seus professores tamb\u00e9m precisam reaprender a melhor maneira de continuar entregando um ensino de qualidade, e o <\/span><b>treinamento adequado<\/b><span style=\"font-weight: 400;\"> do corpo de ensino \u00e9 essencial para garantir uma transi\u00e7\u00e3o de qualidade. <\/span><a href=\"https:\/\/learn.voxy.com\/webinar-melhores-praticas-ensino-online.html\"><span style=\"font-weight: 400;\">Confira nosso webinar para conhecer as melhores pr\u00e1ticas de ensino de idiomas online<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><b>Aproveite a flexibilidade digital<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Uma caracter\u00edstica intr\u00ednseca \u00e0 internet \u00e9 a <\/span><b>flexibilidade<\/b><span style=\"font-weight: 400;\">. Hoje em dia \u00e9 dif\u00edcil estar em algum lugar que n\u00e3o ofere\u00e7a conex\u00e3o por wi-fi ou pelo menos um bom sinal de dados para internet m\u00f3vel. Claro que nem sempre a internet est\u00e1 dispon\u00edvel, e por isso tamb\u00e9m \u00e9 importante oferecer uma <\/span><b>solu\u00e7\u00e3o offline <\/b><span style=\"font-weight: 400;\">que seja acess\u00edvel, mas toda essa conectividade significa que voc\u00ea pode aproveitar essa flexibilidade a favor da sua escola tamb\u00e9m.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Busque uma maneira de oferecer seu ensino n\u00e3o s\u00f3 para acesso em notebooks e desktops, mas tamb\u00e9m para<\/span><b> aparelhos m\u00f3veis como celulares e tablets<\/b><span style=\"font-weight: 400;\">. Atualmente, no Brasil, cada pessoa passa em m\u00e9dia <\/span><b>4 horas e 45 minutos por dia <\/b><span style=\"font-weight: 400;\">mexendo em seus aparelhos pessoais. A transforma\u00e7\u00e3o digital ajuda voc\u00ea a se inserir nesse espa\u00e7o importante do nosso dia-a-dia.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Tamb\u00e9m \u00e9 necess\u00e1rio entender como as pessoas se relacionam com conte\u00fado hoje em dia, e um importante conceito que vem ganhando for\u00e7a nos \u00faltimos tempos \u00e9 o do <\/span><a href=\"https:\/\/voxy.com\/pt-br\/blog\/microaprendizagem-um-metodo-inovador-para-os-programas-de-capacitacao-em-idiomas\/\"><b>microlearning<\/b><\/a><span style=\"font-weight: 400;\">. O per\u00edodo de tempo durante o qual uma pessoa consegue prestar aten\u00e7\u00e3o de verdade em algo espec\u00edfico \u00e9 pequeno, e o microlearning mostra a import\u00e2ncia de oferecer <\/span><b>conte\u00fados curtos <\/b><span style=\"font-weight: 400;\">com os quais as pessoas v\u00e3o interagir e <\/span><b>aprender de verdade<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h2><b>Monitore seu desempenho e resultados<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Uma caracter\u00edstica muito interessante das solu\u00e7\u00f5es digitais \u00e9 que elas permitem a coleta e an\u00e1lise de diversos<\/span><b> dados e informa\u00e7\u00f5es<\/b><span style=\"font-weight: 400;\">, o que \u00e9 extremamente \u00fatil para que sua escola entenda n\u00e3o apenas a <\/span><b>evolu\u00e7\u00e3o<\/b><span style=\"font-weight: 400;\"> de cada estudante ao longo do curso como tamb\u00e9m o<\/span><b> retorno financeiro <\/b><span style=\"font-weight: 400;\">do investimento feito na transforma\u00e7\u00e3o digital em si.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Enquanto seus <\/span><b>professores<\/b><span style=\"font-weight: 400;\"> podem monitorar informa\u00e7\u00f5es como o progresso individual de cada aluno ou turma, o engajamento dos estudantes durante o curso e outras informa\u00e7\u00f5es da performance do ensino, sua <\/span><b>escola<\/b><span style=\"font-weight: 400;\"> pode acompanhar o uso da plataforma digital, o n\u00famero de estudantes ao longo do tempo e outros dados que ajudam identificar os impactos de todas essas movimenta\u00e7\u00f5es nos seus <\/span><b>resultados<\/b><span style=\"font-weight: 400;\"> de neg\u00f3cio.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Se voc\u00ea trabalha em uma escola de ingl\u00eas e quer acompanhar a transforma\u00e7\u00e3o digital para conseguir n\u00e3o apenas<\/span><b> aproveitar as novas oportunidades <\/b><span style=\"font-weight: 400;\">do ensino online como tamb\u00e9m oferecer um aprendizado <\/span><b>ainda melhor <\/b><span style=\"font-weight: 400;\">aos seus estudantes, <\/span><a href=\"https:\/\/voxy.com\/demo\/pt\"><span style=\"font-weight: 400;\">conte com a ajuda da Voxy<\/span><\/a><span style=\"font-weight: 400;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas.<\/p>\n","protected":false},"author":57,"featured_media":24208,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[697],"tags":[],"class_list":["post-24207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-treinamento-e-desenvolvimento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas - Voxy<\/title>\n<meta name=\"description\" content=\"Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas - Voxy\" \/>\n<meta property=\"og:description\" content=\"Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/\" \/>\n<meta property=\"og:site_name\" content=\"Voxy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goVOXY\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-05T16:54:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-20T18:08:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheus Torrano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Voxy\" \/>\n<meta name=\"twitter:site\" content=\"@Voxy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheus Torrano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/\"},\"author\":{\"name\":\"Matheus Torrano\",\"@id\":\"https:\/\/voxy.com\/pt-br\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116\"},\"headline\":\"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas\",\"datePublished\":\"2020-08-05T16:54:27+00:00\",\"dateModified\":\"2020-11-20T18:08:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/\"},\"wordCount\":1030,\"image\":{\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg\",\"articleSection\":[\"Treinamento &amp; Desenvolvimento\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/\",\"url\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/\",\"name\":\"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas - Voxy\",\"isPartOf\":{\"@id\":\"https:\/\/voxy.com\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg\",\"datePublished\":\"2020-08-05T16:54:27+00:00\",\"dateModified\":\"2020-11-20T18:08:03+00:00\",\"author\":{\"@id\":\"https:\/\/voxy.com\/pt-br\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116\"},\"description\":\"Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas.\",\"breadcrumb\":{\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#primaryimage\",\"url\":\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg\",\"contentUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/voxy.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/voxy.com\/pt-br\/#website\",\"url\":\"https:\/\/voxy.com\/pt-br\/\",\"name\":\"Voxy\",\"description\":\"Changing the way the world learns English\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/voxy.com\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/voxy.com\/pt-br\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116\",\"name\":\"Matheus Torrano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/voxy.com\/pt-br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/96e6b2db7fa967e28544cf542e3210cb.jpg?ver=1778672674\",\"contentUrl\":\"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/96e6b2db7fa967e28544cf542e3210cb.jpg?ver=1778672674\",\"caption\":\"Matheus Torrano\"},\"description\":\"Matheus is a Senior Marketing Analyst at Voxy. Part of the Marketing team, he works hard to create valuable experiences that bring more happiness into people\u2019s lives. He has a Bachelor\u2019s degree in Business Administration by FEA-RP\/USP and years of experience in marketing and communication.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/matheustorrano\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas - Voxy","description":"Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/","og_locale":"pt_BR","og_type":"article","og_title":"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas - Voxy","og_description":"Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas.","og_url":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/","og_site_name":"Voxy","article_publisher":"https:\/\/www.facebook.com\/goVOXY\/","article_published_time":"2020-08-05T16:54:27+00:00","article_modified_time":"2020-11-20T18:08:03+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg","type":"image\/jpeg"}],"author":"Matheus Torrano","twitter_card":"summary_large_image","twitter_creator":"@Voxy","twitter_site":"@Voxy","twitter_misc":{"Escrito por":"Matheus Torrano","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#article","isPartOf":{"@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/"},"author":{"name":"Matheus Torrano","@id":"https:\/\/voxy.com\/pt-br\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116"},"headline":"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas","datePublished":"2020-08-05T16:54:27+00:00","dateModified":"2020-11-20T18:08:03+00:00","mainEntityOfPage":{"@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/"},"wordCount":1030,"image":{"@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg","articleSection":["Treinamento &amp; Desenvolvimento"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/","url":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/","name":"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas - Voxy","isPartOf":{"@id":"https:\/\/voxy.com\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#primaryimage"},"image":{"@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#primaryimage"},"thumbnailUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg","datePublished":"2020-08-05T16:54:27+00:00","dateModified":"2020-11-20T18:08:03+00:00","author":{"@id":"https:\/\/voxy.com\/pt-br\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116"},"description":"Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas.","breadcrumb":{"@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#primaryimage","url":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg","contentUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/08\/AdobeStock_351781815-1-scaled.jpeg","width":2560,"height":1707,"caption":"Veja como aproveitar a transforma\u00e7\u00e3o digital para melhorar ainda mais os resultados da sua escola de ingl\u00eas."},{"@type":"BreadcrumbList","@id":"https:\/\/voxy.com\/pt-br\/blog\/a-transformacao-digital-no-ensino-de-idiomas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voxy.com\/"},{"@type":"ListItem","position":2,"name":"A Transforma\u00e7\u00e3o Digital No Ensino De Idiomas"}]},{"@type":"WebSite","@id":"https:\/\/voxy.com\/pt-br\/#website","url":"https:\/\/voxy.com\/pt-br\/","name":"Voxy","description":"Changing the way the world learns English","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voxy.com\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/voxy.com\/pt-br\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116","name":"Matheus Torrano","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/voxy.com\/pt-br\/#\/schema\/person\/image\/","url":"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/96e6b2db7fa967e28544cf542e3210cb.jpg?ver=1778672674","contentUrl":"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/96e6b2db7fa967e28544cf542e3210cb.jpg?ver=1778672674","caption":"Matheus Torrano"},"description":"Matheus is a Senior Marketing Analyst at Voxy. Part of the Marketing team, he works hard to create valuable experiences that bring more happiness into people\u2019s lives. He has a Bachelor\u2019s degree in Business Administration by FEA-RP\/USP and years of experience in marketing and communication.","sameAs":["https:\/\/www.linkedin.com\/in\/matheustorrano\/"]}]}},"_links":{"self":[{"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/posts\/24207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/comments?post=24207"}],"version-history":[{"count":0,"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/posts\/24207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/media\/24208"}],"wp:attachment":[{"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/media?parent=24207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/categories?post=24207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voxy.com\/pt-br\/wp-json\/wp\/v2\/tags?post=24207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}