{"id":130892,"date":"2024-11-19T18:44:34","date_gmt":"2024-11-19T23:44:34","guid":{"rendered":"https:\/\/voxy.com\/su-di-noi\/"},"modified":"2025-12-12T08:00:59","modified_gmt":"2025-12-12T13:00:59","slug":"su-di-noi","status":"publish","type":"page","link":"https:\/\/voxy.com\/it\/su-di-noi\/","title":{"rendered":"Su di noi"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"130892\" class=\"elementor elementor-130892 elementor-129213\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ffb1848 e-flex e-con-boxed e-con e-parent\" data-id=\"ffb1848\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-22fc7bf e-con-full e-flex e-con e-child\" data-id=\"22fc7bf\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b3b2e6d elementor-mobile-align-center elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b3b2e6d\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Scopri Voxy<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29aaf77 elementor-widget-mobile__width-inherit elementor-widget__width-inherit elementor-widget-laptop__width-inherit elementor-widget elementor-widget-heading\" data-id=\"29aaf77\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Dove la formazione linguistica incontra le esigenze aziendali <\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ee87d0 elementor-widget__width-initial elementor-widget-laptop__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1ee87d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Potenzia la produttivit\u00e0 del tuo team con i programmi linguistici su misura di Voxy, progettati per le esigenze della forza lavoro odierna.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f6c2ab e-con-full e-flex e-con e-child\" data-id=\"6f6c2ab\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-061268e elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"061268e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/learn.voxy.com\/demo-it\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Richiedi una Demo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de44bf6 elementor-widget__width-initial elementor-widget-mobile__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"de44bf6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>94.6% di soddisfazione<\/strong> per le lezioni<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-52b7851 e-con-full e-flex e-con e-child\" data-id=\"52b7851\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-818bfe1 elementor-widget elementor-widget-image\" data-id=\"818bfe1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"555\" height=\"531\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png\" class=\"attachment-large size-large wp-image-128781\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png 555w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196-300x287.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196-150x144.png 150w\" sizes=\"(max-width: 555px) 100vw, 555px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e61d842 e-flex e-con-boxed e-con e-parent\" data-id=\"e61d842\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-820024e e-con-full e-flex e-con e-child\" data-id=\"820024e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37b432a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"37b432a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La nostra storia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e7e011 elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3e7e011\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dal 2010 supportiamo aziende in oltre 150 Paesi, offrendo sessioni di coaching linguistico dal vivo tenute da insegnanti qualificati e una vasta gamma di corsi specifici per diverse funzioni. Le nostre soluzioni mirano a colmare le lacune di competenze tecniche e trasversali, aiutando i team a migliorare la comunicazione, aumentare la produttivit\u00e0 e progredire nell&#8217;ambiente aziendale odierno. <\/p>\n<p>Siamo un\u2019 azienda full-remote con membri del team distribuiti in 10 paesi, e abbracciamo la collaborazione globale in tutto ci\u00f2 che facciamo. Per questo, nel 2023, abbiamo ampliato la nostra offerta acquisendo la societ\u00e0 italiana Fluentify, aggiungendo altre opzioni linguistiche oltre all&#8217;inglese per soddisfare meglio le esigenze diversificate dei nostri clienti. <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ccacc2 e-con-full e-flex e-con e-child\" data-id=\"1ccacc2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7a2ab2 elementor-widget elementor-widget-image\" data-id=\"b7a2ab2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1264\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/08\/Team-SP-1-2048x1264.webp\" class=\"attachment-2048x2048 size-2048x2048 wp-image-133654\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/08\/Team-SP-1-2048x1264.webp 2048w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/08\/Team-SP-1-300x185.webp 300w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/08\/Team-SP-1-1024x632.webp 1024w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/08\/Team-SP-1-768x474.webp 768w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/08\/Team-SP-1-1536x948.webp 1536w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/08\/Team-SP-1-150x93.webp 150w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72b4d8a e-flex e-con-boxed e-con e-parent\" data-id=\"72b4d8a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ebb4b49 e-con-full e-flex e-con e-child\" data-id=\"ebb4b49\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-add81c6 elementor-position-left elementor-vertical-align-middle elementor-widget__width-inherit elementor-widget elementor-widget-image-box\" data-id=\"add81c6\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img decoding=\"async\" width=\"26\" height=\"25\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-18-1.png\" class=\"attachment-full size-full wp-image-128811\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><h3 class=\"elementor-image-box-title\">Cronologia<\/h3><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ebe08f e-con-full e-flex e-con e-child\" data-id=\"3ebe08f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e37beae elementor-widget elementor-widget-heading\" data-id=\"e37beae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">2010<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d2cf7a elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"0d2cf7a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Fondazione di Voxy a New York City.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d54e227 e-con-full e-flex e-con e-child\" data-id=\"d54e227\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1ae7a1 elementor-widget elementor-widget-heading\" data-id=\"d1ae7a1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">2017<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6735d6c elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6735d6c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Voxy inizia a concentrarsi esclusivamente sui clienti aziendali, con un approccio basato sulle competenze professionali.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-897e227 e-con-full e-flex e-con e-child\" data-id=\"897e227\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6550711 elementor-widget elementor-widget-heading\" data-id=\"6550711\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">2022<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-12cf55f elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"12cf55f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Voxy acquisisce The Language Co., rafforzando la sua presenza in America Latina.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b8d73f9 e-con-full e-flex e-con e-child\" data-id=\"b8d73f9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ce4418c elementor-widget elementor-widget-heading\" data-id=\"ce4418c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">2023<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f12c130 elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"f12c130\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Voxy aggiunge lo spagnolo, l\u2019italiano, il francese e il tedesco ai suoi programmi di formazione linguistica aziendale grazie all&#8217;acquisizione della societ\u00e0 italiana Fluentify.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8df6ed6 e-con-full e-flex e-con e-child\" data-id=\"8df6ed6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3797629 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"3797629\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"26\" height=\"55\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Frame-427318313.png\" class=\"attachment-large size-large wp-image-128846\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed2396a elementor-widget-mobile__width-inherit elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"ed2396a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"42\" height=\"25\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Frame-427318312-1.png\" class=\"attachment-large size-large wp-image-129183\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56d45b1 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"56d45b1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"42\" height=\"43\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Frame-427318283.png\" class=\"attachment-full size-full wp-image-128830\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><span class=\"elementor-image-box-title\">18+<\/span><p class=\"elementor-image-box-description\">lingue<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-319b0b1 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"319b0b1\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"42\" height=\"43\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Frame-427318283.png\" class=\"attachment-full size-full wp-image-128830\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><span class=\"elementor-image-box-title\">150+<\/span><p class=\"elementor-image-box-description\">paesi<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a8cf23 elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"7a8cf23\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"42\" height=\"43\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Frame-427318283.png\" class=\"attachment-full size-full wp-image-128830\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><span class=\"elementor-image-box-title\">100+<\/span><p class=\"elementor-image-box-description\">corsi specifici per settore<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f9c66a elementor-position-left elementor-vertical-align-middle elementor-widget__width-initial elementor-widget elementor-widget-image-box\" data-id=\"1f9c66a\" data-element_type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><figure class=\"elementor-image-box-img\"><img loading=\"lazy\" decoding=\"async\" width=\"42\" height=\"43\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Frame-427318283.png\" class=\"attachment-full size-full wp-image-128830\" alt=\"\" \/><\/figure><div class=\"elementor-image-box-content\"><span class=\"elementor-image-box-title\">24\/7<\/span><p class=\"elementor-image-box-description\">lezioni dal vivo<\/p><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf49099 e-flex e-con-boxed e-con e-parent\" data-id=\"cf49099\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e14fe11 e-con-full e-flex e-con e-child\" data-id=\"e14fe11\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-097ab04 elementor-widget elementor-widget-image\" data-id=\"097ab04\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"310\" height=\"264\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Users-love-Voxy-on-G2.webp\" class=\"attachment-large size-large wp-image-126152\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Users-love-Voxy-on-G2.webp 310w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Users-love-Voxy-on-G2-300x255.webp 300w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9bf9c0 e-con-full e-flex e-con e-child\" data-id=\"e9bf9c0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7421c6 elementor-widget elementor-widget-image\" data-id=\"d7421c6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"310\" height=\"264\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Voxy-is-a-leader-in-Language-Learning-on-G2.webp\" class=\"attachment-large size-large wp-image-126161\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Voxy-is-a-leader-in-Language-Learning-on-G2.webp 310w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Voxy-is-a-leader-in-Language-Learning-on-G2-300x255.webp 300w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1296ac5 e-con-full e-flex e-con e-child\" data-id=\"1296ac5\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ccaf821 elementor-widget elementor-widget-image\" data-id=\"ccaf821\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"310\" height=\"264\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Brandon-Hall-Group-Gold-Voxy.webp\" class=\"attachment-large size-large wp-image-126143\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Brandon-Hall-Group-Gold-Voxy.webp 310w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Brandon-Hall-Group-Gold-Voxy-300x255.webp 300w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22a94bf e-con-full e-flex e-con e-child\" data-id=\"22a94bf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e4335c elementor-widget elementor-widget-image\" data-id=\"0e4335c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"310\" height=\"264\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Digital-Promise-Product-Certification-Voxy.webp\" class=\"attachment-large size-large wp-image-126170\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Digital-Promise-Product-Certification-Voxy.webp 310w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Digital-Promise-Product-Certification-Voxy-300x255.webp 300w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-68899c8 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"68899c8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a2171b8 elementor-widget elementor-widget-image\" data-id=\"a2171b8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"310\" height=\"264\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Workforce-EdTech-Voxy.webp\" class=\"attachment-large size-large wp-image-126182\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Workforce-EdTech-Voxy.webp 310w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/06\/Workforce-EdTech-Voxy-300x255.webp 300w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-96ccccb e-flex e-con-boxed e-con e-parent\" data-id=\"96ccccb\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5eff176 e-con-full e-flex e-con e-child\" data-id=\"5eff176\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-139105b elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"139105b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vita@Voxy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b88c4c elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"2b88c4c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Siamo un dream team a distanza, distribuito in 10 Paesi e su diversi fusi orari. Nonostante la lontananza geografica, siamo profondamente connessi e collaboriamo in modo efficace, lavorando insieme per raggiungere gli obiettivi comuni. E quando \u00e8 davvero importante, ci incontriamo di persona. <\/p>\n<p>Il nostro respiro globale \u00e8 una delle nostre pi\u00f9 grandi forze, perch\u00e9 ci permette di portare sul tavolo prospettive e competenze diverse, rimanendo per\u00f2 uniti nella nostra missione di abbattere le barriere linguistiche in tutto il mondo.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3ac2500 e-con-full e-flex e-con e-child\" data-id=\"3ac2500\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b88fb35 elementor-widget elementor-widget-image\" data-id=\"b88fb35\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"608\" height=\"326\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-171.png\" class=\"attachment-large size-large wp-image-128858\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-171.png 608w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-171-300x161.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-171-150x80.png 150w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-657ca1c elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"657ca1c\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ee9dba elementor-widget__width-inherit elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-heading\" data-id=\"0ee9dba\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Incontra il nostro team di leadership<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0dc678c e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"0dc678c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6dec42d elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"6dec42d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"232\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/1633690673625-1.png\" class=\"attachment-large size-large wp-image-128872\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/1633690673625-1.png 280w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/1633690673625-1-150x124.png 150w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e87d2d e-con-full e-flex e-con e-child\" data-id=\"0e87d2d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-309b4ea elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"309b4ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tJan Viviani \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a08434 elementor-widget elementor-widget-text-editor\" data-id=\"9a08434\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>CEO <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82f22fe e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"82f22fe\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c46af7 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"6c46af7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"350\" height=\"293\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/Eliane-Iwasaki-1.webp\" class=\"attachment-large size-large wp-image-131359\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/Eliane-Iwasaki-1.webp 350w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/Eliane-Iwasaki-1-300x251.webp 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/Eliane-Iwasaki-1-150x126.webp 150w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05cbc3d e-con-full e-flex e-con e-child\" data-id=\"05cbc3d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89a84bc elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"89a84bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tEliane Yumi Iwasaki \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4767a19 elementor-widget elementor-widget-text-editor\" data-id=\"4767a19\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>SALES &amp; MARKETING <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53cc4d3 e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"53cc4d3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4debb8 elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"d4debb8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"280\" height=\"234\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/1516181681834-1.png\" class=\"attachment-large size-large wp-image-128884\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/1516181681834-1.png 280w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/1516181681834-1-150x125.png 150w\" sizes=\"(max-width: 280px) 100vw, 280px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d7813ea e-con-full e-flex e-con e-child\" data-id=\"d7813ea\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ac6c9b5 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"ac6c9b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tChristopher Osborn \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac9457a elementor-widget elementor-widget-text-editor\" data-id=\"ac9457a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ENGINEERING <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8341964 e-flex e-con-boxed e-con e-parent\" data-id=\"8341964\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ace9756 e-con-full e-flex e-con e-child\" data-id=\"ace9756\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8bff35 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"a8bff35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">I valori di Voxy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e1fe42 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"0e1fe42\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>In Voxy viviamo, respiriamo e condividiamo i nostri valori ogni giorno. Sono la stella polare che guida la nostra azienda e le nostre persone:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f47d5aa e-con-full e-flex e-con e-child\" data-id=\"f47d5aa\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-816970c elementor-widget elementor-widget-image\" data-id=\"816970c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"528\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image4-1-1.png\" class=\"attachment-large size-large wp-image-133271\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image4-1-1.png 472w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image4-1-1-268x300.png 268w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image4-1-1-150x168.png 150w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62dd242 elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"62dd242\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNoi agiamo con empatia \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7ae2c0 elementor-widget elementor-widget-text-editor\" data-id=\"e7ae2c0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Noi crediamo che il vero impatto derivi dal prendere decisioni pratiche guidate dall\u2019empatia.<\/p><p>In Voxy, <b>bilanciamo la sensibilit\u00e0 con il pensiero pragmatico.<\/b> Affrontando le sfide con determinazione e considerando le diverse prospettive e necessit\u00e0 di chi ci circonda, ci assicuriamo che le nostre azioni non siano solo efficaci, ma anche significative per i nostri studenti, clienti e membri del team. Questo approccio ci aiuta a <b>prendere decisioni in linea con la nostra missione.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fd3416d e-con-full e-flex e-con e-child\" data-id=\"fd3416d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a521451 elementor-widget elementor-widget-image\" data-id=\"a521451\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"528\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image1-1.png\" class=\"attachment-large size-large wp-image-133283\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image1-1.png 472w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image1-1-268x300.png 268w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image1-1-150x168.png 150w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66edee7 elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"66edee7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNoi comunichiamo per generare impatto\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e049924 elementor-widget elementor-widget-text-editor\" data-id=\"e049924\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Noi crediamo che una <b>comunicazione coraggiosa possa fare la differenza.<\/b><\/p><p>In Voxy, promuoviamo una cultura di trasparenza e fiducia, <b>incoraggiando conversazioni aperte e ponendo le domande giuste. <\/b>Parliamo con chiarezza e procediamo e con determinazione , adottando un dialogo costruttivo per trovare le migliori soluzioni. <b>La nostra curiosit\u00e0 ci spinge<\/b> a comprendere le esigenze dei nostri studenti, clienti e colleghi, <b>ottenendo risultati che trasformano le vite attraverso l&#8217;apprendimento delle lingue.<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8e486db e-con-full e-flex e-con e-child\" data-id=\"8e486db\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-465100f elementor-widget elementor-widget-image\" data-id=\"465100f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"528\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image2-1.png\" class=\"attachment-large size-large wp-image-133292\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image2-1.png 472w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image2-1-268x300.png 268w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image2-1-150x168.png 150w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-920dd8b elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"920dd8b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNoi accogliamo prospettive diverse per ottenere risultati straordinari\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41b1e92 elementor-widget elementor-widget-text-editor\" data-id=\"41b1e92\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Noi crediamo che <b>prospettive diverse portino a soluzioni migliori.<\/b><\/p><p>In Voxy, il nostro team globale collabora per creare un ambiente in cui tutti si sentano inclusi. <b>Valorizziamo le nostre differenze, <\/b>sapendo che ci permettono di pensare in modo pi\u00f9 intelligente, risolvere i problemi in modo pi\u00f9 efficace e contribuire alla creazione di soluzioni innovative. <b>Abbattiamo le barriere<\/b> per dare alle persone la possibilit\u00e0 di raggiungere i propri obiettivi.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0d693ca e-con-full e-flex e-con e-child\" data-id=\"0d693ca\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f436cf elementor-widget elementor-widget-image\" data-id=\"6f436cf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"472\" height=\"528\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image5-1.png\" class=\"attachment-large size-large wp-image-133301\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image5-1.png 472w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image5-1-268x300.png 268w, https:\/\/voxy.com\/wp-content\/uploads\/2025\/03\/image5-1-150x168.png 150w\" sizes=\"(max-width: 472px) 100vw, 472px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd30fbb elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"bd30fbb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNoi ci assumiamo la responsabilit\u00e0 dei nostri risultati\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-159dcd8 elementor-widget elementor-widget-text-editor\" data-id=\"159dcd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Noi crediamo che la responsabilit\u00e0 favorisca la <b>crescita.<\/b><\/p><p>In Voxy, <b>ogni membro del team deve assumere il proprio ruolo<\/b>, comprendendo che ogni contributo \u00e8 essenziale per sviluppare il nostro prodotto, raggiungere il successo aziendale e offrire soluzioni efficaci ai nostri studenti e clienti.<b> Ci assumiamo la responsabilit\u00e0<\/b> delle nostre azioni, affrontiamo gli ostacoli con determinazione e ci concentriamo sui risultati. Celebriamo i nostri successi come squadra.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-32f940c elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"32f940c\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f81c085 e-con-full e-flex e-con e-child\" data-id=\"f81c085\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eaf4a84 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"eaf4a84\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La nostra missione \u00e8 abbattere le barriere linguistiche<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27d67a6 elementor-widget-tablet__width-inherit elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"27d67a6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSpesso tutto ci\u00f2 che serve \u00e8 un\u2019opportunit\u00e0. E noi vogliamo coglierla. Scopri alcuni progetti ad impatto sociale che scegliamo di sostenere. \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-392781e e-con-full e-flex e-con e-child\" data-id=\"392781e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d18e5f9 e-con-full e-flex e-con e-child\" data-id=\"d18e5f9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca73ba4 elementor-widget elementor-widget-image\" data-id=\"ca73ba4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"608\" height=\"326\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/Dhammajarinee-Witthaya-School-1.png\" class=\"attachment-large size-large wp-image-131045\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/Dhammajarinee-Witthaya-School-1.png 608w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/Dhammajarinee-Witthaya-School-1-300x161.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/Dhammajarinee-Witthaya-School-1-150x80.png 150w\" sizes=\"(max-width: 608px) 100vw, 608px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cca361a e-con-full e-flex e-con e-child\" data-id=\"cca361a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b89f017 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget-laptop__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b89f017\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da oltre vent\u2019anni, la Dhammajarinee Witthaya School garantisce a ragazze svantaggiate della Thailandia un luogo sicuro in cui vivere, pasti e cure mediche, un\u2019istruzione di qualit\u00e0 e un progetto di life skill training.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6d45d23 e-con-full e-flex e-con e-child\" data-id=\"6d45d23\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8e0fcf e-con-full e-flex e-con e-child\" data-id=\"a8e0fcf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d85e123 elementor-widget elementor-widget-image\" data-id=\"d85e123\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"66\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/6310f0d64e50b01fc1d276e3_LOGOS_VDD_01_MARROM-1-1.png\" class=\"attachment-large size-large wp-image-131054\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/6310f0d64e50b01fc1d276e3_LOGOS_VDD_01_MARROM-1-1.png 251w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/11\/6310f0d64e50b01fc1d276e3_LOGOS_VDD_01_MARROM-1-1-150x39.png 150w\" sizes=\"(max-width: 251px) 100vw, 251px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc5f659 e-con-full e-flex e-con e-child\" data-id=\"bc5f659\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d62ce76 elementor-widget__width-initial elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"d62ce76\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Focalizzata su imprenditori di origine africana e microimprese del nord e del nord-est del Brasile, Vale do Dend\u00ea sostiene organizzazioni che puntano sull\u2019innovazione, sulla diversit\u00e0 e sulla sostenibilit\u00e0.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-204715a e-flex e-con-boxed e-con e-parent\" data-id=\"204715a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7228b96 e-con-full e-flex e-con e-child\" data-id=\"7228b96\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-58f6a41 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"58f6a41\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La conoscenza attecchisce quando \u00e8 coinvolgente, pertinente e basata su esperienze personali.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7a51f2a elementor-widget-laptop__width-initial elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"7a51f2a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La piattaforma Voxy, aggiornata quotidianamente con contenuti di qualit\u00e0 provenienti da partner selezionati, offre lezioni in pillole e corsi rapidi per potenziare i tuoi team. Scopri alcuni dei nostri partner per i contenuti: <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f71327 e-con-full e-flex e-con e-child\" data-id=\"1f71327\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12f179d elementor-widget elementor-widget-image\" data-id=\"12f179d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"142\" height=\"84\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/bp_economist-1-1.png\" class=\"attachment-large size-large wp-image-129035\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-514d44b e-con-full e-flex e-con e-child\" data-id=\"514d44b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f858db elementor-widget elementor-widget-image\" data-id=\"9f858db\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"160\" height=\"112\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Voxy-About-Us-4.png\" class=\"attachment-large size-large wp-image-129026\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Voxy-About-Us-4.png 160w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Voxy-About-Us-4-150x105.png 150w\" sizes=\"(max-width: 160px) 100vw, 160px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d5f97a e-con-full e-flex e-con e-child\" data-id=\"1d5f97a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9a1adc3 elementor-widget elementor-widget-image\" data-id=\"9a1adc3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"132\" height=\"92\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Voxy-About-Us-3.png\" class=\"attachment-large size-large wp-image-129017\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4858299 e-con-full e-flex e-con e-child\" data-id=\"4858299\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fda9585 elementor-widget elementor-widget-image\" data-id=\"fda9585\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"132\" height=\"92\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Voxy-About-Us-1.png\" class=\"attachment-large size-large wp-image-129008\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e91565d e-flex e-con-boxed e-con e-parent\" data-id=\"e91565d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f90b2b3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f90b2b3\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-308b028 e-flex e-con-boxed e-con e-parent\" data-id=\"308b028\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dc3d1ef e-con-full e-flex e-con e-child\" data-id=\"dc3d1ef\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ecd2800 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"ecd2800\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Conosciamo le sfide specifiche di ogni settore<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34c8c60 elementor-widget-laptop__width-initial elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"34c8c60\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u2026 e molti altri corsi specifici per settore per potenziare i team. <a href=\"https:\/\/voxy.com\/it\/corsi-di-inglese\/\">Vedi tutti i corsi &gt; &gt;<\/a><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fab01a4 e-con-full e-flex e-con e-child\" data-id=\"fab01a4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4acddb0 elementor-widget elementor-widget-image\" data-id=\"4acddb0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"177\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5.png\" class=\"attachment-large size-large wp-image-129090\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5.png 380w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-300x140.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-150x70.png 150w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd5daa1 e-con-full e-flex e-con e-child\" data-id=\"bd5daa1\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5ed19 elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"3d5ed19\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLanguages for IT Professionals \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-76d7a9e e-con-full e-flex e-con e-child\" data-id=\"76d7a9e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a69cc9d elementor-widget elementor-widget-image\" data-id=\"a69cc9d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"177\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-1.png\" class=\"attachment-large size-large wp-image-129081\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-1.png 380w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-1-300x140.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-1-150x70.png 150w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2fc059f e-con-full e-flex e-con e-child\" data-id=\"2fc059f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9ddc7a2 elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"9ddc7a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLanguages for Financial Companies \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3219f50 e-con-full e-flex e-con e-child\" data-id=\"3219f50\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db06f6e elementor-widget elementor-widget-image\" data-id=\"db06f6e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"177\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-2.png\" class=\"attachment-large size-large wp-image-129072\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-2.png 380w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-2-300x140.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-2-150x70.png 150w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d9ce1c6 e-con-full e-flex e-con e-child\" data-id=\"d9ce1c6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e2465bc elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"e2465bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLanguages for Leaders and Managers \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcccdd0 e-con-full e-flex e-con e-child\" data-id=\"bcccdd0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-46306c3 elementor-widget elementor-widget-image\" data-id=\"46306c3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"177\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-3.png\" class=\"attachment-large size-large wp-image-129063\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-3.png 380w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-3-300x140.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-3-150x70.png 150w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7030171 e-con-full e-flex e-con e-child\" data-id=\"7030171\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29b1f23 elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"29b1f23\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLanguages for Customer Success \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-251306f e-con-full e-flex e-con e-child\" data-id=\"251306f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c19e8c elementor-widget elementor-widget-image\" data-id=\"6c19e8c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"177\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-4.png\" class=\"attachment-large size-large wp-image-129054\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-4.png 380w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-4-300x140.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-4-150x70.png 150w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f338cb7 e-con-full e-flex e-con e-child\" data-id=\"f338cb7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cf3fe8a elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"cf3fe8a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tLanguages Project Management \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-70817c9 e-con-full e-flex e-con e-child\" data-id=\"70817c9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-27b8df3 elementor-widget elementor-widget-image\" data-id=\"27b8df3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"177\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-5.png\" class=\"attachment-large size-large wp-image-129045\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-5.png 380w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-5-300x140.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/image-5-5-150x70.png 150w\" sizes=\"(max-width: 380px) 100vw, 380px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4c2096 e-con-full e-flex e-con e-child\" data-id=\"e4c2096\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0617178 elementor-widget-tablet__width-inherit elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"0617178\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tBest Languages Practices for Remote Teams \t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ed48f32 e-flex e-con-boxed e-con e-parent\" data-id=\"ed48f32\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dd823ed e-con-full e-flex e-con e-child\" data-id=\"dd823ed\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7aa8029 e-con-full e-flex e-con e-child\" data-id=\"7aa8029\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-751111a elementor-widget elementor-widget-image\" data-id=\"751111a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"42\" height=\"25\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Frame-427318312.png\" class=\"attachment-large size-large wp-image-129106\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e97323c elementor-widget__width-inherit elementor-widget elementor-widget-heading\" data-id=\"e97323c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unisciti al team Voxy<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6bad09e elementor-widget__width-inherit elementor-widget-tablet__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"6bad09e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unisciti a un team di professionisti curiosi, appassionati e orientati all&#8217;azione e costruiamo la piattaforma di apprendimento linguistico pi\u00f9 efficace e innovativa al mondo.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15bbdd2 elementor-mobile-align-justify elementor-align-left elementor-widget elementor-widget-button\" data-id=\"15bbdd2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/voxy.com\/it\/carriere\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Vedi posizioni aperte<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-588f204 e-con-full e-flex e-con e-child\" data-id=\"588f204\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b55539f elementor-widget elementor-widget-image\" data-id=\"b55539f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"398\" height=\"433\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-189.png\" class=\"attachment-large size-large wp-image-129116\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-189.png 398w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-189-276x300.png 276w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-189-150x163.png 150w\" sizes=\"(max-width: 398px) 100vw, 398px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Scopri Voxy Dove la formazione linguistica incontra le esigenze aziendali Potenzia la produttivit\u00e0 del tuo team con i programmi linguistici su misura di Voxy, progettati per le esigenze della forza lavoro odierna. Richiedi una Demo 94.6% di soddisfazione per le lezioni La nostra storia Dal 2010 supportiamo aziende in oltre 150 Paesi, offrendo sessioni di [&#8230;]\n","protected":false},"author":78,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-130892","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Su di noi - Voxy<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voxy.com\/it\/su-di-noi\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Su di noi - Voxy\" \/>\n<meta property=\"og:description\" content=\"Scopri Voxy Dove la formazione linguistica incontra le esigenze aziendali Potenzia la produttivit\u00e0 del tuo team con i programmi linguistici su misura di Voxy, progettati per le esigenze della forza lavoro odierna. Richiedi una Demo 94.6% di soddisfazione per le lezioni La nostra storia Dal 2010 supportiamo aziende in oltre 150 Paesi, offrendo sessioni di [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voxy.com\/it\/su-di-noi\/\" \/>\n<meta property=\"og:site_name\" content=\"Voxy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goVOXY\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T13:00:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"887\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Voxy\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/voxy.com\/it\/su-di-noi\/\",\"url\":\"https:\/\/voxy.com\/it\/su-di-noi\/\",\"name\":\"Su di noi - Voxy\",\"isPartOf\":{\"@id\":\"https:\/\/voxy.com\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/voxy.com\/it\/su-di-noi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/voxy.com\/it\/su-di-noi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png\",\"datePublished\":\"2024-11-19T23:44:34+00:00\",\"dateModified\":\"2025-12-12T13:00:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/voxy.com\/it\/su-di-noi\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/voxy.com\/it\/su-di-noi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/voxy.com\/it\/su-di-noi\/#primaryimage\",\"url\":\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png\",\"contentUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/voxy.com\/it\/su-di-noi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/voxy.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Su di noi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/voxy.com\/it\/#website\",\"url\":\"https:\/\/voxy.com\/it\/\",\"name\":\"Voxy\",\"description\":\"Changing the way the world learns English\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/voxy.com\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Su di noi - Voxy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voxy.com\/it\/su-di-noi\/","og_locale":"it_IT","og_type":"article","og_title":"Su di noi - Voxy","og_description":"Scopri Voxy Dove la formazione linguistica incontra le esigenze aziendali Potenzia la produttivit\u00e0 del tuo team con i programmi linguistici su misura di Voxy, progettati per le esigenze della forza lavoro odierna. Richiedi una Demo 94.6% di soddisfazione per le lezioni La nostra storia Dal 2010 supportiamo aziende in oltre 150 Paesi, offrendo sessioni di [...]","og_url":"https:\/\/voxy.com\/it\/su-di-noi\/","og_site_name":"Voxy","article_publisher":"https:\/\/www.facebook.com\/goVOXY\/","article_modified_time":"2025-12-12T13:00:59+00:00","og_image":[{"width":1080,"height":887,"url":"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Voxy","twitter_misc":{"Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/voxy.com\/it\/su-di-noi\/","url":"https:\/\/voxy.com\/it\/su-di-noi\/","name":"Su di noi - Voxy","isPartOf":{"@id":"https:\/\/voxy.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voxy.com\/it\/su-di-noi\/#primaryimage"},"image":{"@id":"https:\/\/voxy.com\/it\/su-di-noi\/#primaryimage"},"thumbnailUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png","datePublished":"2024-11-19T23:44:34+00:00","dateModified":"2025-12-12T13:00:59+00:00","breadcrumb":{"@id":"https:\/\/voxy.com\/it\/su-di-noi\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voxy.com\/it\/su-di-noi\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/voxy.com\/it\/su-di-noi\/#primaryimage","url":"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png","contentUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2024\/09\/Group-196.png"},{"@type":"BreadcrumbList","@id":"https:\/\/voxy.com\/it\/su-di-noi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voxy.com\/"},{"@type":"ListItem","position":2,"name":"Su di noi"}]},{"@type":"WebSite","@id":"https:\/\/voxy.com\/it\/#website","url":"https:\/\/voxy.com\/it\/","name":"Voxy","description":"Changing the way the world learns English","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voxy.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/voxy.com\/it\/wp-json\/wp\/v2\/pages\/130892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voxy.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/voxy.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/voxy.com\/it\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/voxy.com\/it\/wp-json\/wp\/v2\/comments?post=130892"}],"version-history":[{"count":15,"href":"https:\/\/voxy.com\/it\/wp-json\/wp\/v2\/pages\/130892\/revisions"}],"predecessor-version":[{"id":134206,"href":"https:\/\/voxy.com\/it\/wp-json\/wp\/v2\/pages\/130892\/revisions\/134206"}],"wp:attachment":[{"href":"https:\/\/voxy.com\/it\/wp-json\/wp\/v2\/media?parent=130892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}