{"id":25649,"date":"2020-12-29T11:50:10","date_gmt":"2020-12-29T16:50:10","guid":{"rendered":"https:\/\/voxy.com\/?p=25649"},"modified":"2020-12-29T11:50:10","modified_gmt":"2020-12-29T16:50:10","slug":"capacitacion-online-las-ventajas-para-la-capacitacion-empresarial","status":"publish","type":"post","link":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/","title":{"rendered":"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial"},"content":{"rendered":"<p><em><strong>M\u00e1s que una necesidad, la capacitaci\u00f3n online puede ser un gran aliado para los profesionales de capacitaci\u00f3n y desarrollo (C&amp;D). Conozca las principales ventajas de esta modalidad para empresas.<\/strong><\/em><\/p>\n<p><span style=\"font-weight: 400;\">El cambio de miles de profesionales en todo el mundo hacia un r\u00e9gimen de trabajo a distancia ha hecho que las empresas necesiten <\/span><b>adaptar r\u00e1pidamente sus procesos y pr\u00e1cticas<\/b><span style=\"font-weight: 400;\"> a esta nueva realidad digital.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s de buscar plataformas y herramientas que permitieran a los equipos seguir realizando sus actividades rutinarias y atendiendo a los clientes sin interrupciones, las empresas tambi\u00e9n necesitaban buscar formas de <\/span><b>mantener la formaci\u00f3n de sus empleados<\/b><span style=\"font-weight: 400;\">, incluso sin la posibilidad de promover reuniones presenciales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En este nuevo escenario, la alternativa de la capacitaci\u00f3n online surge como una gran soluci\u00f3n, ya que esta modalidad permite no solo mantener los programas de capacitaci\u00f3n sin ning\u00fan impacto negativo en la calidad, sino que tambi\u00e9n aporta varias <\/span><b>ventajas en relaci\u00f3n al entrenamiento tradicional<\/b><span style=\"font-weight: 400;\"> realizado de forma presencial.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Hablando con clientes internacionales de Voxy, identificamos algunas de las principales ventajas vistas<\/span><b> en la pr\u00e1ctica<\/b><span style=\"font-weight: 400;\"> por los profesionales que decidieron iniciar o ampliar sus iniciativas de capacitaci\u00f3n en ingl\u00e9s mediante el entorno digital, y ahora puedes ver cu\u00e1les fueron estos aspectos destacados.<\/span><\/p>\n<h2><span style=\"font-weight: 400;\">Principales ventajas de la capacitaci\u00f3n online<\/span><\/h2>\n<h3><span style=\"font-weight: 400;\">Mejor costo-beneficio<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Mientras la capacitaci\u00f3n presencial implica costos intr\u00ednsecos como gastos de log\u00edstica, materiales f\u00edsicos, viajes, espacio para capacitaci\u00f3n y cualquier otro tipo de infraestructura necesaria, la capacitaci\u00f3n en l\u00ednea <\/span><b>elimina todos estos costos<\/b><span style=\"font-weight: 400;\"> al agregar toda la informaci\u00f3n de capacitaci\u00f3n en una plataforma en l\u00ednea basada en internet.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De esta manera, los empleados pueden acceder al contenido del programa de capacitaci\u00f3n directamente desde sus tel\u00e9fonos celulares o computadoras en cualquier lugar que ofrezca acceso a Internet, reduciendo a cero los costos log\u00edsticos presentes en la alternativa presencial. Algunas empresas incluso informaron de una<\/span><b> reducci\u00f3n de hasta un 55%<\/b><span style=\"font-weight: 400;\"> en el valor total de la capacitaci\u00f3n tras optar por la migraci\u00f3n de sus programas al entorno digital.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Escalabilidad e inclusi\u00f3n<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Una ventaja tambi\u00e9n relacionada con la reducci\u00f3n de costos es la <\/span><b>mayor escalabilidad e inclusi\u00f3n <\/b><span style=\"font-weight: 400;\">que permite la capacitaci\u00f3n en l\u00ednea.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con menores costos, las empresas pueden ampliar el alcance de sus programas de capacitaci\u00f3n para atender a una mayor cantidad de empleados con<\/span><b> el mismo presupuesto<\/b><span style=\"font-weight: 400;\"> que se invertir\u00eda en capacitaci\u00f3n presencial, haciendo este tipo de iniciativas m\u00e1s inclusivas dentro de las organizaciones.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Adem\u00e1s, la capacitaci\u00f3n en l\u00ednea es mucho m\u00e1s escalable debido a su <\/span><b>facilidad para cambiar los empleados inscritos <\/b><span style=\"font-weight: 400;\">en el programa. Si bien los entrenamientos presenciales implican una burocracia considerable para eliminar o incluir de manera efectiva a los empleados en el programa, en la capacitaci\u00f3n en l\u00ednea el administrador solo necesita actualizar el registro de correo electr\u00f3nico con acceso a la plataforma.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Mayor visibilidad y control<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Otra facilidad que brinda el uso de la tecnolog\u00eda en la capacitaci\u00f3n en l\u00ednea es el f\u00e1cil acceso a <\/span><b>m\u00e9tricas e indicadores claros<\/b><span style=\"font-weight: 400;\"> para monitorear el desempe\u00f1o tanto de las personas como del programa en su conjunto.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Las buenas plataformas de formaci\u00f3n online ofrecen <\/span><b>reportes<\/b><span style=\"font-weight: 400;\"> constantemente actualizados sobre el <\/span><a href=\"https:\/\/voxy.com\/es\/blog\/mantenga-a-los-empleados-comprometidos-con-un-programa-de-capacitacion-100-en-linea\/\"><span style=\"font-weight: 400;\">involucramiento de los empleados<\/span><\/a><span style=\"font-weight: 400;\">, la evoluci\u00f3n de las habilidades cubiertas por la formaci\u00f3n y diversas m\u00e9tricas que permiten a los profesionales responsables de estas actividades tomar decisiones m\u00e1s conscientes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Teniendo m\u00e1s visibilidad del avance de cada programa de formaci\u00f3n, los equipos de C&amp;D pueden identificar puntos de atenci\u00f3n y realizar ajustes a lo largo del programa, como iniciativas para fomentar el involucramiento o incluso transferir el acceso al programa entre los empleados, <\/span><b>optimizando la inversi\u00f3n realizada<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Gesti\u00f3n del tiempo y flexibilidad<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">El acceso a internet tanto a trav\u00e9s de redes wifi como de datos es cada vez m\u00e1s f\u00e1cil en nuestra sociedad, y toda esta disponibilidad permite a los empleados que participan en la capacitaci\u00f3n online, tener una <\/span><b>mayor flexibilidad<\/b><span style=\"font-weight: 400;\"> en su dedicaci\u00f3n a los estudios.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sin necesidad de desplazarse f\u00edsicamente a un lugar de capacitaci\u00f3n, los empleados informan\u00a0 una<\/span><b> mejora en la calidad de vida<\/b><span style=\"font-weight: 400;\"> tras iniciar la participaci\u00f3n en programas de capacitaci\u00f3n en l\u00ednea, ya que esta alternativa permite realizar los estudios en los momentos m\u00e1s adecuados para cada profesional.<\/span><\/p>\n<h3><span style=\"font-weight: 400;\">Contenido personalizado y actualizado<\/span><\/h3>\n<p><span style=\"font-weight: 400;\">Sin las limitaciones presentes en los materiales f\u00edsicos utilizados en la capacitaci\u00f3n en el aula, los profesionales que participan en la capacitaci\u00f3n en l\u00ednea tienen acceso a una amplia variedad de contenido, que puede optimizarse a\u00fan m\u00e1s con el uso de tecnolog\u00edas de <\/span><b>inteligencia artificial<\/b><span style=\"font-weight: 400;\"> para <\/span><a href=\"https:\/\/voxy.com\/es\/blog\/por-que-es-importante-la-personalizacion-para-el-aprendizaje-de-idiomas-online\/\"><span style=\"font-weight: 400;\">personalizar<\/span><\/a><span style=\"font-weight: 400;\"> y <\/span><b>actualizar el contenido<\/b><span style=\"font-weight: 400;\"> con las necesidades de cada colaborador.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">De esta forma, la capacitaci\u00f3n online es una alternativa que consigue no solo un <\/span><b>alto<\/b> <b>involucramiento<\/b><span style=\"font-weight: 400;\"> de los empleados inscritos en el programa, sino tambi\u00e9n una <\/span><b>ense\u00f1anza<\/b> <b>m\u00e1s<\/b> <b>eficaz<\/b><span style=\"font-weight: 400;\">, ofreciendo informaci\u00f3n realmente relevante e interesante para cada individuo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Con tantas ventajas que superan a la capacitaci\u00f3n presencial, queda claro por qu\u00e9 los programas en l\u00ednea est\u00e1n <\/span><b>ganando cada vez m\u00e1s espacio<\/b><span style=\"font-weight: 400;\"> en las empresas que quieren optimizar sus iniciativas de C&amp;D. Si quieres saber m\u00e1s sobre esta y otras tendencias en capacitaci\u00f3n empresarial, consulta nuestro ebook: <\/span><b>\u00ab<\/b><a href=\"https:\/\/learn.voxy.com\/ebook-tendencias-de-la-transformacion-digital-en-la-capacitacion-empresarial.html\"><b>Tendencias de la transformaci\u00f3n digital en la capacitaci\u00f3n empresarial<\/b><\/a><b>\u00ab<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para obtener m\u00e1s informaci\u00f3n sobre c\u00f3mo Voxy combina <\/span><b>tecnolog\u00eda innovadora y metodolog\u00eda eficaz<\/b><span style=\"font-weight: 400;\"> para ofrecer una <\/span><b>capacitaci\u00f3n de ingl\u00e9s en l\u00ednea<\/b><span style=\"font-weight: 400;\"> incomparable, <\/span><a href=\"https:\/\/voxy.com\/demo\/es\"><span style=\"font-weight: 400;\">solicite una demostraci\u00f3n<\/span><\/a><span style=\"font-weight: 400;\"> de la plataforma con nuestro equipo de <\/span><b>Global Solutions<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s que una necesidad, la capacitaci\u00f3n online puede ser un gran aliado para los profesionales de capacitaci\u00f3n y desarrollo (C&#038;D). Conozca las principales ventajas de esta modalidad para empresas.<\/p>\n","protected":false},"author":57,"featured_media":25650,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[698],"tags":[],"class_list":["post-25649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capacitacion-y-desarrollo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial - Voxy<\/title>\n<meta name=\"description\" content=\"M\u00e1s que una necesidad, la capacitaci\u00f3n online puede ser un gran aliado para los profesionales de capacitaci\u00f3n y desarrollo (C&amp;D). Conozca las principales ventajas de esta modalidad para empresas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial - Voxy\" \/>\n<meta property=\"og:description\" content=\"M\u00e1s que una necesidad, la capacitaci\u00f3n online puede ser un gran aliado para los profesionales de capacitaci\u00f3n y desarrollo (C&amp;D). Conozca las principales ventajas de esta modalidad para empresas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/\" \/>\n<meta property=\"og:site_name\" content=\"Voxy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goVOXY\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-29T16:50:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Matheus Torrano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Voxy\" \/>\n<meta name=\"twitter:site\" content=\"@Voxy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Matheus Torrano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/\"},\"author\":{\"name\":\"Matheus Torrano\",\"@id\":\"https:\/\/voxy.com\/es\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116\"},\"headline\":\"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial\",\"datePublished\":\"2020-12-29T16:50:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/\"},\"wordCount\":991,\"image\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg\",\"articleSection\":[\"Capacitaci\u00f3n Y Desarrollo\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/\",\"url\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/\",\"name\":\"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial - Voxy\",\"isPartOf\":{\"@id\":\"https:\/\/voxy.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg\",\"datePublished\":\"2020-12-29T16:50:10+00:00\",\"author\":{\"@id\":\"https:\/\/voxy.com\/es\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116\"},\"description\":\"M\u00e1s que una necesidad, la capacitaci\u00f3n online puede ser un gran aliado para los profesionales de capacitaci\u00f3n y desarrollo (C&D). Conozca las principales ventajas de esta modalidad para empresas.\",\"breadcrumb\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#primaryimage\",\"url\":\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg\",\"contentUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg\",\"width\":2560,\"height\":1707,\"caption\":\"Woman Working From Home Using Laptop On Dining Table\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/voxy.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/voxy.com\/es\/#website\",\"url\":\"https:\/\/voxy.com\/es\/\",\"name\":\"Voxy\",\"description\":\"Learn a language from life\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/voxy.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/voxy.com\/es\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116\",\"name\":\"Matheus Torrano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/voxy.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/96e6b2db7fa967e28544cf542e3210cb.jpg?ver=1778672674\",\"contentUrl\":\"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/96e6b2db7fa967e28544cf542e3210cb.jpg?ver=1778672674\",\"caption\":\"Matheus Torrano\"},\"description\":\"Matheus is a Senior Marketing Analyst at Voxy. Part of the Marketing team, he works hard to create valuable experiences that bring more happiness into people\u2019s lives. He has a Bachelor\u2019s degree in Business Administration by FEA-RP\/USP and years of experience in marketing and communication.\",\"sameAs\":[\"https:\/\/www.linkedin.com\/in\/matheustorrano\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial - Voxy","description":"M\u00e1s que una necesidad, la capacitaci\u00f3n online puede ser un gran aliado para los profesionales de capacitaci\u00f3n y desarrollo (C&D). Conozca las principales ventajas de esta modalidad para empresas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/","og_locale":"es_ES","og_type":"article","og_title":"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial - Voxy","og_description":"M\u00e1s que una necesidad, la capacitaci\u00f3n online puede ser un gran aliado para los profesionales de capacitaci\u00f3n y desarrollo (C&D). Conozca las principales ventajas de esta modalidad para empresas.","og_url":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/","og_site_name":"Voxy","article_publisher":"https:\/\/www.facebook.com\/goVOXY\/","article_published_time":"2020-12-29T16:50:10+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg","type":"image\/jpeg"}],"author":"Matheus Torrano","twitter_card":"summary_large_image","twitter_creator":"@Voxy","twitter_site":"@Voxy","twitter_misc":{"Escrito por":"Matheus Torrano","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#article","isPartOf":{"@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/"},"author":{"name":"Matheus Torrano","@id":"https:\/\/voxy.com\/es\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116"},"headline":"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial","datePublished":"2020-12-29T16:50:10+00:00","mainEntityOfPage":{"@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/"},"wordCount":991,"image":{"@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg","articleSection":["Capacitaci\u00f3n Y Desarrollo"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/","url":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/","name":"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial - Voxy","isPartOf":{"@id":"https:\/\/voxy.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#primaryimage"},"image":{"@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#primaryimage"},"thumbnailUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg","datePublished":"2020-12-29T16:50:10+00:00","author":{"@id":"https:\/\/voxy.com\/es\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116"},"description":"M\u00e1s que una necesidad, la capacitaci\u00f3n online puede ser un gran aliado para los profesionales de capacitaci\u00f3n y desarrollo (C&D). Conozca las principales ventajas de esta modalidad para empresas.","breadcrumb":{"@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#primaryimage","url":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg","contentUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2020\/12\/AdobeStock_135317132-1-scaled.jpeg","width":2560,"height":1707,"caption":"Woman Working From Home Using Laptop On Dining Table"},{"@type":"BreadcrumbList","@id":"https:\/\/voxy.com\/es\/blog\/capacitacion-online-las-ventajas-para-la-capacitacion-empresarial\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voxy.com\/"},{"@type":"ListItem","position":2,"name":"Capacitaci\u00f3n online: las ventajas para la capacitaci\u00f3n empresarial"}]},{"@type":"WebSite","@id":"https:\/\/voxy.com\/es\/#website","url":"https:\/\/voxy.com\/es\/","name":"Voxy","description":"Learn a language from life","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voxy.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/voxy.com\/es\/#\/schema\/person\/b5bf6cc4e75f3fe8e1b17cd0c42dc116","name":"Matheus Torrano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/voxy.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/96e6b2db7fa967e28544cf542e3210cb.jpg?ver=1778672674","contentUrl":"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/96e6b2db7fa967e28544cf542e3210cb.jpg?ver=1778672674","caption":"Matheus Torrano"},"description":"Matheus is a Senior Marketing Analyst at Voxy. Part of the Marketing team, he works hard to create valuable experiences that bring more happiness into people\u2019s lives. He has a Bachelor\u2019s degree in Business Administration by FEA-RP\/USP and years of experience in marketing and communication.","sameAs":["https:\/\/www.linkedin.com\/in\/matheustorrano\/"]}]}},"_links":{"self":[{"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/posts\/25649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/comments?post=25649"}],"version-history":[{"count":0,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/posts\/25649\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/media\/25650"}],"wp:attachment":[{"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/media?parent=25649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/categories?post=25649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/tags?post=25649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}