{"id":120360,"date":"2023-07-31T17:11:46","date_gmt":"2023-07-31T21:11:46","guid":{"rendered":"https:\/\/voxy.com\/?p=120360"},"modified":"2025-01-23T13:39:28","modified_gmt":"2025-01-23T18:39:28","slug":"contratacion-basada-en-habilidades","status":"publish","type":"post","link":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/","title":{"rendered":"Contrataci\u00f3n Basada en Habilidades: la Clave para Organizaciones Preparadas para el Futuro"},"content":{"rendered":"\n<p>Las organizaciones en todo el mundo enfrentan desaf\u00edos crecientes para encontrar miembros calificados para sus equipos debido a una escasez global de mano de obra. La Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos <a href=\"https:\/\/www.pmi.org\/learning\/thought-leadership\/megatrends\/2022\/labor-shortages\">descubri\u00f3<\/a> que actualmente hay 20 millones menos de personas trabajando en comparaci\u00f3n con los tiempos previos a la pandemia de COVID-19. <\/p>\n\n\n\n<p>Para abordar este problema, las empresas \u00e1giles est\u00e1n recurriendo a la <strong>contrataci\u00f3n basada en habilidades<\/strong>, lo que les permite identificar, reclutar y desarrollar talento altamente capacitado de manera efectiva.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es la contrataci\u00f3n basada en habilidades?<\/h2>\n\n\n\n<p><strong>La contrataci\u00f3n basada en habilidades es un enfoque revolucionario que eval\u00faa a los posibles miembros del equipo en funci\u00f3n de sus habilidades en lugar de su experiencia y educaci\u00f3n.<\/strong><\/p>\n\n\n\n<p>A diferencia de los m\u00e9todos de contrataci\u00f3n tradicionales, este enfoque ampl\u00eda el grupo de talentos al no tener en cuenta criterios arbitrarios, como un n\u00famero espec\u00edfico de a\u00f1os de experiencia o un t\u00edtulo.<\/p>\n\n\n\n<p>\u00abLos empleadores deben centrarse en las habilidades al tomar decisiones de contrataci\u00f3n y restar importancia a los t\u00edtulos y conexiones\u00bb, <a href=\"https:\/\/fortune-com.cdn.ampproject.org\/c\/s\/fortune.com\/2022\/11\/23\/skills-replacing-college-degrees-hiring-linkedin-ceo-ryan-roslansky\/amp\/\">afirma Ryan Roslansky<\/a>, CEO de LinkedIn. <\/p>\n\n\n\n<p>Seg\u00fan \u00e9l, un enfoque basado en habilidades crea un mercado laboral mucho m\u00e1s eficiente y <a href=\"\/?page_id=23949\">equitativo<\/a>, lo que a su vez genera mejores oportunidades para todos.<\/p>\n\n\n\n<p>Las organizaciones preparadas para el futuro utilizan el reclutamiento basado en habilidades junto con otros programas, como el desarrollo de habilidades (<a href=\"https:\/\/voxy.com\/es\/blog\/upskilling-y-reskilling\/\">upskilling<\/a>) y el trabajo <a href=\"https:\/\/www.gallup.com\/workplace\/397751\/returning-office-current-preferred-future-state-remote-work.aspx\">remoto<\/a> o h\u00edbrido, para lograr una mayor diversidad en su pipeline de talento.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1les son los beneficios de la contrataci\u00f3n basada en habilidades?<\/h2>\n\n\n\n<p>La contrataci\u00f3n centrada en habilidades o <em>skills-based hiring<\/em> elimina requisitos de trabajo innecesarios y <strong>se centra en las habilidades necesarias para desempe\u00f1ar el trabajo<\/strong> y <a href=\"https:\/\/www.gallup.com\/cliftonstrengths\/en\/278225\/how-to-improve-teamwork.aspx\">colaborar<\/a> bien con los miembros del equipo.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Al eliminar barreras artificiales, se puede aumentar la <a href=\"https:\/\/voxy.com\/es\/blog\/diversidad-en-el-trabajo\/\">diversidad<\/a> de su equipo. Los equipos diversos suelen ser m\u00e1s creativos e innovadores debido a las diferentes perspectivas de sus miembros.<\/li>\n\n\n\n<li>Contar con un conocimiento m\u00e1s amplio de diferentes culturas o regiones dentro de su equipo tambi\u00e9n puede aumentar las oportunidades comerciales.<\/li>\n\n\n\n<li>Los empleados cuyas habilidades coinciden con sus trabajos tienden a estar <a href=\"https:\/\/learning.linkedin.com\/content\/dam\/me\/learning\/en-us\/pdfs\/workplace-learning-report\/LinkedIn-Learning_Workplace-Learning-Report-2023-EN.pdf\">m\u00e1s involucrados<\/a> y permanecer m\u00e1s tiempo en la organizaci\u00f3n.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-2.jpg\" alt=\"contrataci\u00f3n basada en habilidades\" class=\"wp-image-120332\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-2.jpg 800w, https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-2-300x150.jpg 300w, https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-2-768x384.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-white-color has-alpha-channel-opacity has-white-background-color has-background\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Implementaci\u00f3n de la Contrataci\u00f3n Basada en Habilidades<\/h2>\n\n\n\n<p>Contratar personal por habilidades requiere replantear todo el proceso de reclutamiento, desde el principio hasta el final.<\/p>\n\n\n\t\t<div data-elementor-type=\"container\" data-elementor-id=\"130472\" class=\"elementor elementor-130472\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-887dd13 e-flex e-con-boxed e-con e-parent\" data-id=\"887dd13\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0a301e elementor-widget elementor-widget-image\" data-id=\"a0a301e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/learn.voxy.com\/corporate-language-training-es.html?utm_source=website&#038;utm_medium=blog&#038;utm_campaign=ebook-corporate-learning&#038;utm_content=banner-a-es\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1020\" height=\"408\" src=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/10\/ES-1.png\" class=\"attachment-large size-large wp-image-132244\" alt=\"\" srcset=\"https:\/\/voxy.com\/wp-content\/uploads\/2024\/10\/ES-1.png 1024w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/10\/ES-1-300x120.png 300w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/10\/ES-1-768x308.png 768w, https:\/\/voxy.com\/wp-content\/uploads\/2024\/10\/ES-1-150x60.png 150w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\n\n\n<h3 class=\"wp-block-heading\">Reescribir Descripciones de Puestos<\/h3>\n\n\n\n<p>El primer paso en la contrataci\u00f3n basada en habilidades es reescribir las descripciones de puestos para centrarse en responsabilidades y competencias cr\u00edticas, eliminando requisitos irrelevantes que podr\u00edan ser una barrera para que personas calificadas apliquen.<\/p>\n\n\n\n<p>Seg\u00fan <a href=\"https:\/\/joshbersin.com\/2023\/07\/building-a-skills-based-organization-the-exciting-but-sober-reality\/\">Josh Bersin<\/a>, las habilidades se dividen en varias categor\u00edas: t\u00e9cnicas, operativas, funcionales, conocimientos espec\u00edficos de la industria y habilidades de <a href=\"https:\/\/voxy.com\/es\/blog\/habilidades-de-comunicacion\/\">comunicaci\u00f3n<\/a> o interpersonales, como el liderazgo.<\/p>\n\n\n\n<p>La comunicaci\u00f3n en varios idiomas se est\u00e1 convirtiendo en una habilidad crucial para muchas organizaciones. Los empleados biling\u00fces ayudan a las empresas a expandirse y generar contenido para nuevos mercados.<\/p>\n\n\n\n<p>Tambi\u00e9n suelen aportar una perspectiva cultural \u00fanica. <a href=\"https:\/\/www.nih.gov\/news-events\/news-releases\/bilinguals-switch-tasks-faster-monolinguals-nih-funded-study-shows\">Estudios<\/a> demuestran que los empleados biling\u00fces pueden cambiar de tareas m\u00e1s r\u00e1pidamente que los monoling\u00fces, lo que los convierte en activos en un entorno empresarial en constante cambio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">B\u00fasqueda Proactiva<\/h3>\n\n\n\n<p>El reclutamiento exitoso requiere una b\u00fasqueda proactiva de candidatos. En lugar de simplemente listar un trabajo en un sitio de b\u00fasqueda de empleo, establezca relaciones con socios de b\u00fasqueda, como programas de certificaci\u00f3n y organizaciones profesionales cuyos miembros son principalmente minor\u00edas.<\/p>\n\n\n\n<p>Los ejecutivos de la empresa tambi\u00e9n deber\u00edan asistir regularmente a conferencias de la industria para conocer a personas altamente talentosas.<\/p>\n\n\n\n<p>Las organizaciones que necesitan una habilidad en particular deber\u00edan considerar asistir a conferencias o eventos en regiones geogr\u00e1ficas donde se concentran esas habilidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reducir el Sesgo Inconsciente<\/h3>\n\n\n\n<p>A menudo, las empresas examinan r\u00e1pidamente los curr\u00edculos, especialmente con los <a href=\"https:\/\/www.forbes.com\/sites\/forbesbusinesscouncil\/2022\/06\/10\/artificial-intelligence-in-hiring-a-tool-for-recruiters\/?sh=4055f9703200\">avances en IA<\/a> en los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p>Los sesgos inconscientes pueden infiltrarse en el proceso a menos que desarrolle <strong>criterios de selecci\u00f3n y los compare con las habilidades del solicitante<\/strong>.<\/p>\n\n\n\n<p>No necesariamente descarte a candidatos que tengan la mayor\u00eda de las habilidades, pero que carezcan de algunas. El espacio en un curr\u00edculo es limitado y los candidatos pueden listar solo algunas cosas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Desarrollar un Proceso de Entrevista Estructurado<\/h3>\n\n\n\n<p>Haga las mismas preguntas a cada candidato en el mismo orden para asegurarse de compararlos con los mismos criterios. <\/p>\n\n\n\n<p>Realice preguntas abiertas sobre comportamientos; por ejemplo, cu\u00e9nteme sobre una vez que tuvo que persuadir a alguien para que realizara una tarea de manera diferente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ejecutar An\u00e1lisis de Evaluaci\u00f3n de Habilidades<\/h3>\n\n\n\n<p>Cree su propia evaluaci\u00f3n de habilidades. Por ejemplo, si busca a un ingeniero de software, p\u00eddale que complete un desaf\u00edo de escritura de c\u00f3digo.<\/p>\n\n\n\n<p>Aseg\u00farese de <a href=\"https:\/\/www.forbes.com\/sites\/forbeshumanresourcescouncil\/2022\/05\/11\/how-employers-can-approach-validating-skills-assessments\/?sh=720d78597bd4\">validar<\/a> la evaluaci\u00f3n en t\u00e9rminos de eficacia y precisi\u00f3n y aseg\u00farese de que no descarte posibles contrataciones debido a criterios injustos o irrelevantes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Reconsiderar las Verificaciones de Antecedentes<\/h3>\n\n\n\n<p>Si las verificaciones de antecedentes son demasiado detalladas, pueden proporcionar informaci\u00f3n irrelevante que su equipo usa inconscientemente para descartar solicitantes con talento potencial. Aseg\u00farese de que las verificaciones de antecedentes <strong>se centren solo en factores relevantes para el trabajo<\/strong>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ser Flexible<\/h3>\n\n\n\n<p>Sea flexible en cuanto a los arreglos laborales. El mejor empleado para su equipo puede vivir lejos y no estar dispuesto a mudarse, por ejemplo. O puede preferir trabajar seis horas durante el d\u00eda cuando su hijo est\u00e1 en la escuela y dos horas por la noche despu\u00e9s de que su hijo se duerma.<\/p>\n\n\n\n<p>Una encuesta realizada por McKinsey en Estados Unidos revel\u00f3 que <a href=\"https:\/\/www.mckinsey.com\/industries\/real-estate\/our-insights\/americans-are-embracing-flexible-work-and-they-want-more-of-it\">el 58% de las personas entrevistadas<\/a>, en varios puestos y empresas, considera que la mayor parte de su trabajo puede realizarse de forma remota.<\/p>\n\n\n\n<p>Si los<a href=\"https:\/\/www.hrdive.com\/spons\/4-reasons-companies-build-distributed-workforces-by-hiring-remote-talent\/610875\/\"> costos laborales<\/a> son un problema, su organizaci\u00f3n puede encontrar un miembro talentoso del equipo en otro pa\u00eds donde el costo de vida es menor. <\/p>\n\n\n\n<p>No todos los trabajos son adecuados para el trabajo remoto o flexible, pero los empleadores que ofrecen estas opciones tienen una <a href=\"https:\/\/www.roberthalf.com\/us\/en\/insights\/management-tips\/4-tips-for-hiring-in-a-tight-labor-market\">ventaja en el reclutamiento.<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ofrecer Oportunidades de Desarrollo<\/h3>\n\n\n\n<p>Los empleados tambi\u00e9n desean unirse a empresas que los ayuden a desarrollar sus habilidades. Aproximadamente el<a href=\"https:\/\/www.forbes.com\/sites\/markcperna\/2022\/10\/31\/74-of-millennials--gen-z-think-they-can-build-better-skills-at-a-new-job\/?sh=1bf7b6b0a313\"> 75% de los trabajadores de la Generaci\u00f3n Z<\/a> dicen que dejar\u00edan empleos que no ofrecen oportunidades para desarrollar habilidades. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.gartner.com\/en\/human-resources\/role\/learning-development\">M\u00e1s de la mitad<\/a> de todos los trabajadores dicen que necesitan oportunidades de desarrollo de habilidades.<\/p>\n\n\n\n<p>El <a href=\"https:\/\/voxy.com\/es\/blog\/upskilling-y-reskilling\/\">desarrollo de habilidades (upskilling) y el reciclaje de habilidades (re-skilling)<\/a> son cruciales para una organizaci\u00f3n orientada hacia el futuro. <\/p>\n\n\n\n<p>Los equipos directivos deber\u00edan mapear regularmente las habilidades que tienen en el equipo con las necesidades futuras y buscar formas de cubrir cualquier brecha con capacitaci\u00f3n.<\/p>\n\n\n\n<p>Desarrollar personas para futuras posiciones dentro de la empresa <a href=\"https:\/\/www.linkedin.com\/business\/talent\/blog\/learning-and-development\/what-is-upskilling\">suele ser menos costoso<\/a> que reclutar para esos puestos externamente. El desarrollo de habilidades tambi\u00e9n mejora la participaci\u00f3n y la moral de los empleados, lo que a su vez mejora la productividad y la retenci\u00f3n.<\/p>\n\n\n\n<p><strong>Las empresas m\u00e1s exitosas ofrecen a los empleados diversas oportunidades para desarrollar habilidades<\/strong>, incluidas habilidades funcionales, digitales y habilidades blandas, como la comunicaci\u00f3n y las relaciones. Tambi\u00e9n utilizan diferentes <a href=\"https:\/\/hbr.org\/2022\/04\/6-strategies-to-upskill-your-workforce\">metodolog\u00edas de aprendizaje<\/a>.<\/p>\n\n\n\n<p>Voxy puede ser una valiosa aliada para sus planes de capacitaci\u00f3n y actualizaci\u00f3n de habilidades de su equipo, ofreciendo un entrenamiento que desarrolla idiomas y habilidades profesionales al mismo tiempo.<\/p>\n\n\n\n<p>Tambi\u00e9n proporcionamos un servicio basado en datos que identifica brechas de habilidades y determina las necesidades de idiomas para cada puesto. Cont\u00e1ctenos para <a href=\"https:\/\/learn.voxy.com\/demo-es.html\">solicitar una demostraci\u00f3n<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las organizaciones en todo el mundo enfrentan desaf\u00edos crecientes para encontrar miembros calificados para sus equipos debido a una escasez global de mano de obra. La Organizaci\u00f3n para la Cooperaci\u00f3n y el Desarrollo Econ\u00f3micos descubri\u00f3 que actualmente hay 20 millones menos de personas trabajando en comparaci\u00f3n con los tiempos previos a la pandemia de COVID-19. [&#8230;]\n","protected":false},"author":70,"featured_media":120330,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[735],"tags":[],"class_list":["post-120360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tendencias-y-hr-insights"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Contrataci\u00f3n basada en habilidades: la clave para organizaciones preparadas para el futuro<\/title>\n<meta name=\"description\" content=\"Ampl\u00ede su grupo de talentos, fomente la diversidad y aumente la retenci\u00f3n de empleados con el poder de la contrataci\u00f3n basada en habilidades.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Contrataci\u00f3n basada en habilidades: la clave para organizaciones preparadas para el futuro\" \/>\n<meta property=\"og:description\" content=\"Ampl\u00ede su grupo de talentos, fomente la diversidad y aumente la retenci\u00f3n de empleados con el poder de la contrataci\u00f3n basada en habilidades.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Voxy\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/goVOXY\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-31T21:11:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-23T18:39:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1148\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mariana Montezzana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Voxy\" \/>\n<meta name=\"twitter:site\" content=\"@Voxy\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Montezzana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/\"},\"author\":{\"name\":\"Mariana Montezzana\",\"@id\":\"https:\/\/voxy.com\/es\/#\/schema\/person\/d981ecde0e3644877b94ef3029d1ee84\"},\"headline\":\"Contrataci\u00f3n Basada en Habilidades: la Clave para Organizaciones Preparadas para el Futuro\",\"datePublished\":\"2023-07-31T21:11:46+00:00\",\"dateModified\":\"2025-01-23T18:39:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/\"},\"wordCount\":1312,\"image\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg\",\"articleSection\":[\"Tendencias &amp; HR Insights\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/\",\"url\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/\",\"name\":\"Contrataci\u00f3n basada en habilidades: la clave para organizaciones preparadas para el futuro\",\"isPartOf\":{\"@id\":\"https:\/\/voxy.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg\",\"datePublished\":\"2023-07-31T21:11:46+00:00\",\"dateModified\":\"2025-01-23T18:39:28+00:00\",\"author\":{\"@id\":\"https:\/\/voxy.com\/es\/#\/schema\/person\/d981ecde0e3644877b94ef3029d1ee84\"},\"description\":\"Ampl\u00ede su grupo de talentos, fomente la diversidad y aumente la retenci\u00f3n de empleados con el poder de la contrataci\u00f3n basada en habilidades.\",\"breadcrumb\":{\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#primaryimage\",\"url\":\"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg\",\"contentUrl\":\"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg\",\"width\":1148,\"height\":500,\"caption\":\"contrataci\u00f3n basada en habilidades\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/voxy.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contrataci\u00f3n Basada en Habilidades: la Clave para Organizaciones Preparadas para el Futuro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/voxy.com\/es\/#website\",\"url\":\"https:\/\/voxy.com\/es\/\",\"name\":\"Voxy\",\"description\":\"Learn a language from life\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/voxy.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/voxy.com\/es\/#\/schema\/person\/d981ecde0e3644877b94ef3029d1ee84\",\"name\":\"Mariana Montezzana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/voxy.com\/es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/6d8dc107e26cdc252055f1793e24d67b.jpg?ver=1778672237\",\"contentUrl\":\"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/6d8dc107e26cdc252055f1793e24d67b.jpg?ver=1778672237\",\"caption\":\"Mariana Montezzana\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Contrataci\u00f3n basada en habilidades: la clave para organizaciones preparadas para el futuro","description":"Ampl\u00ede su grupo de talentos, fomente la diversidad y aumente la retenci\u00f3n de empleados con el poder de la contrataci\u00f3n basada en habilidades.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/","og_locale":"es_ES","og_type":"article","og_title":"Contrataci\u00f3n basada en habilidades: la clave para organizaciones preparadas para el futuro","og_description":"Ampl\u00ede su grupo de talentos, fomente la diversidad y aumente la retenci\u00f3n de empleados con el poder de la contrataci\u00f3n basada en habilidades.","og_url":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/","og_site_name":"Voxy","article_publisher":"https:\/\/www.facebook.com\/goVOXY\/","article_published_time":"2023-07-31T21:11:46+00:00","article_modified_time":"2025-01-23T18:39:28+00:00","og_image":[{"width":1148,"height":500,"url":"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg","type":"image\/jpeg"}],"author":"Mariana Montezzana","twitter_card":"summary_large_image","twitter_creator":"@Voxy","twitter_site":"@Voxy","twitter_misc":{"Escrito por":"Mariana Montezzana","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#article","isPartOf":{"@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/"},"author":{"name":"Mariana Montezzana","@id":"https:\/\/voxy.com\/es\/#\/schema\/person\/d981ecde0e3644877b94ef3029d1ee84"},"headline":"Contrataci\u00f3n Basada en Habilidades: la Clave para Organizaciones Preparadas para el Futuro","datePublished":"2023-07-31T21:11:46+00:00","dateModified":"2025-01-23T18:39:28+00:00","mainEntityOfPage":{"@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/"},"wordCount":1312,"image":{"@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#primaryimage"},"thumbnailUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg","articleSection":["Tendencias &amp; HR Insights"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/","url":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/","name":"Contrataci\u00f3n basada en habilidades: la clave para organizaciones preparadas para el futuro","isPartOf":{"@id":"https:\/\/voxy.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#primaryimage"},"image":{"@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#primaryimage"},"thumbnailUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg","datePublished":"2023-07-31T21:11:46+00:00","dateModified":"2025-01-23T18:39:28+00:00","author":{"@id":"https:\/\/voxy.com\/es\/#\/schema\/person\/d981ecde0e3644877b94ef3029d1ee84"},"description":"Ampl\u00ede su grupo de talentos, fomente la diversidad y aumente la retenci\u00f3n de empleados con el poder de la contrataci\u00f3n basada en habilidades.","breadcrumb":{"@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#primaryimage","url":"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg","contentUrl":"https:\/\/voxy.com\/wp-content\/uploads\/2023\/07\/skills-based-hiring-1.jpg","width":1148,"height":500,"caption":"contrataci\u00f3n basada en habilidades"},{"@type":"BreadcrumbList","@id":"https:\/\/voxy.com\/es\/blog\/contratacion-basada-en-habilidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/voxy.com\/"},{"@type":"ListItem","position":2,"name":"Contrataci\u00f3n Basada en Habilidades: la Clave para Organizaciones Preparadas para el Futuro"}]},{"@type":"WebSite","@id":"https:\/\/voxy.com\/es\/#website","url":"https:\/\/voxy.com\/es\/","name":"Voxy","description":"Learn a language from life","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/voxy.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/voxy.com\/es\/#\/schema\/person\/d981ecde0e3644877b94ef3029d1ee84","name":"Mariana Montezzana","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/voxy.com\/es\/#\/schema\/person\/image\/","url":"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/6d8dc107e26cdc252055f1793e24d67b.jpg?ver=1778672237","contentUrl":"https:\/\/voxy.com\/wp-content\/litespeed\/avatar\/6d8dc107e26cdc252055f1793e24d67b.jpg?ver=1778672237","caption":"Mariana Montezzana"}}]}},"_links":{"self":[{"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/posts\/120360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/comments?post=120360"}],"version-history":[{"count":0,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/posts\/120360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/media\/120330"}],"wp:attachment":[{"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/media?parent=120360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/categories?post=120360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voxy.com\/es\/wp-json\/wp\/v2\/tags?post=120360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}